{"id":11,"date":"2025-11-29T17:26:08","date_gmt":"2025-11-29T16:26:08","guid":{"rendered":"https:\/\/nuestrosescritores.com\/sabelagondulfes\/?page_id=11"},"modified":"2025-11-29T23:29:34","modified_gmt":"2025-11-29T22:29:34","slug":"sabela-gondulfes","status":"publish","type":"page","link":"https:\/\/nuestrosescritores.com\/sabelagondulfes\/","title":{"rendered":"SABELA GONDULFES"},"content":{"rendered":"<div class=\"wpb-content-wrapper\" id=\"wpb-content-root\">[vc_row full_width=&#8221;stretch_row_content_no_spaces&#8221; full_height=&#8221;yes&#8221; equal_height=&#8221;yes&#8221;][vc_column extend=&#8221;false&#8221;][layerslider_vc id=&#8221;2&#8243;][layerslider_vc id=&#8221;1&#8243;][\/vc_column][\/vc_row][vc_row extend=&#8221;false&#8221; design__empty_1=&#8221;&#8221; background=&#8221;&#8221; background_image_type=&#8221;static&#8221; background_image__effect=&#8221;&#8221; bg_size=&#8221;initial&#8221; bg_position=&#8221;center-center&#8221; row_bg_image=&#8221;&#8221; bg_repeat=&#8221;no-repeat&#8221; background_image_type__bg_color=&#8221;rgba(255, 255, 255, 1)&#8221; row_bg_parallax_images=&#8221;&#8221; row_bg_slideshow_images=&#8221;&#8221; background_video_type=&#8221;youtube&#8221; background_video__youtube__url=&#8221;&#8221; background_video__youtube__parallax=&#8221;&#8221; background_video__youtube__options=&#8221;&#8221; background_video__youtube__fallback_image=&#8221;&#8221; background_video__hosted__mp4=&#8221;&#8221; background_video__hosted__webm=&#8221;&#8221; background_video__hosted__ogv=&#8221;&#8221; background_video__hosted__parallax=&#8221;&#8221; background_video__hosted__options=&#8221;&#8221; background_video__hosted__fallback_image=&#8221;&#8221; background_color_type=&#8221;color&#8221; bg__empty_1=&#8221;&#8221; background_color_type__gradient_color1=&#8221;rgba(44, 74, 228, 1)&#8221; background_color_type__gradient_color2=&#8221;rgba(44, 74, 228, 1)&#8221; background_color_type__color_color1=&#8221;rgba(44, 74, 228, 1)&#8221; bg__empty_2=&#8221;&#8221; background_color__effect=&#8221;&#8221; background_color__direction=&#8221;left-to-right&#8221; settings__tag_1=&#8221;&#8221; viewport_lg=&#8221;&#8221; viewport_md=&#8221;&#8221; viewport_sm=&#8221;&#8221; viewport_xs=&#8221;&#8221; settings__empty_1=&#8221;&#8221; version=&#8221;1&#8243;][vc_column width=&#8221;1\/2&#8243; extend=&#8221;false&#8221;]<div class=\"ult-content-box-container \" >\t\t<div class=\"ult-content-box\" style=\"background-color:rgba(255,255,255,0.49);box-shadow: px px 8px px #f2f2f2 none;border-style:none;-webkit-transition: all 700ms ease;-moz-transition: all 700ms ease;-ms-transition: all 700ms ease;-o-transition: all 700ms ease;transition: all 700ms ease;\"  data-hover_box_shadow=\"none\"     data-bg=\"rgba(255,255,255,0.49)\"  data-border_color=\"\" >[vc_column_text css=&#8221;.vc_custom_1764433181479{padding-top: 15% !important;padding-right: 15% !important;padding-bottom: 15% !important;padding-left: 15% !important;}&#8221;]<strong>SABELA GONDULFES<\/strong><\/p>\n<p>Hay escritoras que escriben porque estudiaron literatura. Sabela Gondulfes escribe porque si no lo hiciera, probablemente estallar\u00eda. Nacida en Gondulfes, una aldea de Ourense donde los r\u00edos a\u00fan tienen nombre propio y las monta\u00f1as guardan secretos en gallego, aprendi\u00f3 a leer el mundo antes de saber escribirlo. Su infancia transcurri\u00f3 descalza entre margaritas, subida a \u00e1rboles comiendo fruta de temporada, ayudando en faenas que hoy la denunciar\u00edan al juez de menores. Fue feliz, dice, &#8220;en medio de una tristeza subyacente&#8221;. Esa contradicci\u00f3n \u2014alegr\u00eda atravesada de sombra\u2014 marca toda su poes\u00eda.<\/p>\n<p>A diferencia de muchas poetas de su generaci\u00f3n que escriben desde la biblioteca o la academia, Gondulfes escribe desde la carretera. Su biograf\u00eda es un mapa de desplazamientos: Vigo, Madrid, Rennes, Vannes, Nueva York, Buenos Aires, Villa La Angostura en la Patagonia argentina, Isla Negra, Santiago de Chile, San Pedro de Atacama, Lisboa, Elvas en el Alentejo portugu\u00e9s. Cada ciudad dej\u00f3 marca, cada paisaje se convirti\u00f3 en verso. Pero siempre vuelve, al menos con las palabras, a esa Galicia que es origen y herida.<\/p>\n<p>Estudi\u00f3 Psicolog\u00eda y Ciencias de la Informaci\u00f3n en la Complutense madrile\u00f1a, combinaci\u00f3n que explica mucho: sabe mirar dentro de las personas y sabe c\u00f3mo contarlo. Su primera novela, <em>En la Penumbra<\/em>, qued\u00f3 finalista en el V Concurso Internacional Luis Berenguer, confirmando que su talento no se limitaba al verso. Pero es en la poes\u00eda donde Gondulfes se reconoce completamente. Ha publicado <em>Inv\u00e9ntame la Vida<\/em> (con C\u00e9sar P\u00f3o), <em>PielanDo<\/em> \u2014presentado en la m\u00edtica Fundaci\u00f3n Neruda, en Isla Negra, ese santuario donde los poetas peregrinan\u2014, y <em>Deshilachando Banderas<\/em> con Nadar Ediciones.<\/p>\n<p>Sus poemas han viajado m\u00e1s que ella: forman parte de antolog\u00edas iberoamericanas, participaron del proyecto colectivo <em>gira poema 2009<\/em> que conect\u00f3 Santiago de Chile con Nueva York, y han sido musicalizados en jazz fusion y blues. Hay algo en su poes\u00eda que pide m\u00fasica, que necesita el cuerpo m\u00e1s all\u00e1 de la p\u00e1gina. No es casual que sus versos hayan sido traducidos al ruso, chino, georgiano e italiano, y recitados en escenarios tan diversos como un bar de Buenos Aires, una librer\u00eda de Lisboa o un festival de poes\u00eda en Galicia. Su voz trasciende fronteras porque habla de lo universal desde lo profundamente personal.<\/p>\n<p>Lo que distingue a Gondulfes de otras voces po\u00e9ticas actuales es su negativa a elegir. Cultiva poes\u00eda, narrativa, cr\u00f3nica de viaje, ensayo, y recientemente se ha lanzado al dibujo y la literatura infantil. No se especializa porque la vida no cabe en un solo g\u00e9nero. Escribe, dice, &#8220;desde que no sab\u00eda escribir. Entonces lo hac\u00eda a trav\u00e9s de s\u00edmbolos y dibujos&#8221;. Esa escritura anterior a la escritura, esa urgencia que no espera t\u00e9cnica ni permiso, sigue intacta en cada verso.<\/p>\n<p>Su poes\u00eda no es de las que se leen en silencio y soledad. Es poes\u00eda para decir en voz alta, para compartir en la sobremesa, para gritar si hace falta. Cuando escribe &#8220;La poes\u00eda es el arma que me mantiene viva y libre&#8221;, no es met\u00e1fora: es declaraci\u00f3n literal de supervivencia. Ha hecho de la escritura trinchera, refugio, territorio propio en un mundo que constantemente intenta moldear a las mujeres seg\u00fan patrones ajenos.<\/p>\n<p>Gondulfes pertenece a esa estirpe de poetas \u2014m\u00e1s com\u00fan en Latinoam\u00e9rica que en Espa\u00f1a\u2014 que no separan vida y escritura, que convierten cada experiencia en materia verbal. No escribe sobre la vida: escribe la vida mientras la vive. Sus lectores no encuentran en ella perfecci\u00f3n formal sino autenticidad radical, esa rara honestidad de quien se atreve a decir &#8220;te amo&#8221; sin iron\u00eda protectora, &#8220;me duele&#8221; sin pudor intelectual, &#8220;estoy furiosa&#8221; sin disculparse.<\/p>\n<p>Ahora, con <em>AFOUTEZA &amp; CERTE\u00c7A<\/em>, su nuevo poemario que fusiona gallego y portugu\u00e9s desde el t\u00edtulo mismo, Gondulfes confirma una voz necesaria: la de quien escribe porque el silencio ser\u00eda traici\u00f3n. En tiempos donde tanta poes\u00eda espa\u00f1ola se ha vuelto contenida, pulcra, casi as\u00e9ptica, ella reivindica el derecho al desbordamiento. Su poes\u00eda puede ser irregular, excesiva, desigual. Y precisamente por eso es imprescindible.<\/p>\n<p>Vive entre Galicia y el mundo, entre el espa\u00f1ol y el gallego, entre la p\u00e1gina y la calle. Sigue escribiendo como quien respira: sin pedir permiso, sin esperar reconocimientos, porque es lo \u00fanico que sabe hacer cuando la vida aprieta demasiado o cuando la belleza la desborda. &#8220;Amo profundo mi tierra natal&#8221;, dice, &#8220;aun as\u00ed, me considero universal&#8221;. Esa es Sabela Gondulfes: radicalmente gallega y radicalmente del mundo, poeta de la aldea y del planeta, voz que canta en todas las lenguas que habita porque ninguna le alcanza para decir todo lo que necesita decir.<\/p>\n<p><strong>&nbsp;<\/strong><\/p>\n<p><strong>&nbsp;<\/strong><\/p>\n<span class='bctt-click-to-tweet'><span class='bctt-ctt-text'><a href='https:\/\/x.com\/intent\/tweet?url=https%3A%2F%2Fnuestrosescritores.com%2Fsabelagondulfes%2F&#038;text=SABELA%20GONDULFES%20.%20Escritora%2C%20poeta.&#038;related' target='_blank'rel=\"noopener noreferrer\">SABELA GONDULFES . Escritora, poeta. <\/a><\/span><a href='https:\/\/x.com\/intent\/tweet?url=https%3A%2F%2Fnuestrosescritores.com%2Fsabelagondulfes%2F&#038;text=SABELA%20GONDULFES%20.%20Escritora%2C%20poeta.&#038;related' target='_blank' class='bctt-ctt-btn'rel=\"noopener noreferrer\">Compartir en X<\/a><\/span>[\/vc_column_text]\t\t<\/div><\/div>[\/vc_column][vc_column width=&#8221;1\/2&#8243; extend=&#8221;false&#8221;]<div class=\"gambit_fullheight_row\" data-content-location=\"center\" style=\"display: none\"><\/div><div id=\"rowvcpt-row-settings\" class=\"rowvcpt-row-set RowVcPt-row-setting6a93ab834eb1b \" data-no=\"RowVcPt-row-setting6a93ab834eb1b\"><div  id=\"bgGallaryslide6a93ab834eb2c\" class=\"rowvcpt-slideshow \"><\/div><script type=\"text\/javascript\">\n(function($) {\n$(\"#bgGallaryslide6a93ab834eb2c\").vegas({\n        overlay: \"https:\/\/nuestrosescritores.com\/sabelagondulfes\/wp-content\/plugins\/ultimate-row-background\/css\/overlays\/0'.esc_attr(1.png).'\",\n        transitionDuration: 4e3,\n        delay: 7000,\n        slides: [{src: \"https:\/\/nuestrosescritores.com\/sabelagondulfes\/wp-content\/uploads\/sites\/224\/2025\/11\/Firefly_Runway_-Semilla-de-luz-flotando-en-un-vasto-cosmos-oscuro-de-ella-emergen-raices-que-se-con-12035.webp\",transition: \"fade2\",transitionDuration: 5000},{src: \"https:\/\/nuestrosescritores.com\/sabelagondulfes\/wp-content\/uploads\/sites\/224\/2025\/11\/Firefly_Runway_-Silueta-femenina-integrada-con-paisaje-de-montanas-gallegas-al-atardecer-su-cabello-645515.webp\",transition: \"fade2\",transitionDuration: 5000},{src: \"https:\/\/nuestrosescritores.com\/sabelagondulfes\/wp-content\/uploads\/sites\/224\/2025\/11\/Firefly_Runway_-Vientre-femenino-como-universo-conteniendo-galaxias-rios-de-luz-y-semillas-germinan-12035.webp\",transition: \"fade2\",transitionDuration: 5000},{src: \"https:\/\/nuestrosescritores.com\/sabelagondulfes\/wp-content\/uploads\/sites\/224\/2025\/11\/Firefly_-Semilla-de-luz-flotando-en-un-vasto-cosmos-oscuro-de-ella-emergen-raices-que-se-con-514076.webp\",transition: \"fade2\",transitionDuration: 5000},]\n    });\t\t\n})(jQuery);\n<\/script><div class=\"rowvcpt-overlay\" style=\"background:rgba(255,255,255,0.69)\"><\/div><\/div>[vc_single_image image=&#8221;27&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; css=&#8221;&#8221;][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text css=&#8221;&#8221;]\n<audio class=\"wp-audio-shortcode\" id=\"audio-11-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/nuestrosescritores.com\/sabelagondulfes\/wp-content\/uploads\/sites\/224\/2025\/11\/Autora_Sabela_Gondulfes_la_urgencia_volcanica_de_escribir.mp3?_=1\" \/><a href=\"https:\/\/nuestrosescritores.com\/sabelagondulfes\/wp-content\/uploads\/sites\/224\/2025\/11\/Autora_Sabela_Gondulfes_la_urgencia_volcanica_de_escribir.mp3\">https:\/\/nuestrosescritores.com\/sabelagondulfes\/wp-content\/uploads\/sites\/224\/2025\/11\/Autora_Sabela_Gondulfes_la_urgencia_volcanica_de_escribir.mp3<\/a><\/audio>\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row full_height=&#8221;yes&#8221; equal_height=&#8221;yes&#8221;][vc_column extend=&#8221;false&#8221;]<div id=\"rowvcpt-row-settings\" class=\"rowvcpt-row-set RowVcPt-row-setting6a93ab834f745 \" data-no=\"RowVcPt-row-setting6a93ab834f745\"><div class=\"columns-bg-wrap columns-bg-anim-colors columns-bg-image  columns_simple_image\" id=\"RowVcPt-image-bg-6a93ab834f744\"   data-parallax_sense=\"30\" src=\"https:\/\/nuestrosescritores.com\/sabelagondulfes\/wp-content\/uploads\/sites\/224\/2025\/11\/Editor_Firefly_-Mujer-de-espaldas-con-panuelo-rojo-ondeando-al-viento-en-paisaje-de-valles-y-montana-827074.webp\" style=\"background-image: url(https:\/\/nuestrosescritores.com\/sabelagondulfes\/wp-content\/uploads\/sites\/224\/2025\/11\/Editor_Firefly_-Mujer-de-espaldas-con-panuelo-rojo-ondeando-al-viento-en-paisaje-de-valles-y-montana-827074.webp);background-size: cover;background-attachment: fixed;\"><\/div><\/div>[\/vc_column][\/vc_row][vc_row][vc_column extend=&#8221;false&#8221;]<div class=\"gambit_fullheight_row\" data-content-location=\"center\" style=\"display: none\"><\/div><div id=\"rowvcpt-row-settings\" class=\"rowvcpt-row-set RowVcPt-row-setting6a93ab834fab5 \" data-no=\"RowVcPt-row-setting6a93ab834fab5\"><div  id=\"bgGallaryslide6a93ab834fab9\" class=\"rowvcpt-slideshow \"><\/div><script type=\"text\/javascript\">\n(function($) {\n$(\"#bgGallaryslide6a93ab834fab9\").vegas({\n        overlay: \"https:\/\/nuestrosescritores.com\/sabelagondulfes\/wp-content\/plugins\/ultimate-row-background\/css\/overlays\/0'.esc_attr(1.png).'\",\n        transitionDuration: 4e3,\n        delay: 7000,\n        slides: [{src: \"https:\/\/nuestrosescritores.com\/sabelagondulfes\/wp-content\/uploads\/sites\/224\/2025\/11\/Firefly_Runway_-Silueta-femenina-integrada-con-paisaje-de-montanas-gallegas-al-atardecer-su-cabello-645515.webp\",transition: \"fade2\",transitionDuration: 5000},{src: \"https:\/\/nuestrosescritores.com\/sabelagondulfes\/wp-content\/uploads\/sites\/224\/2025\/11\/Firefly_Runway_-Vientre-femenino-como-universo-conteniendo-galaxias-rios-de-luz-y-semillas-germinan-12035.webp\",transition: \"fade2\",transitionDuration: 5000},{src: \"https:\/\/nuestrosescritores.com\/sabelagondulfes\/wp-content\/uploads\/sites\/224\/2025\/11\/Firefly_-Semilla-de-luz-flotando-en-un-vasto-cosmos-oscuro-de-ella-emergen-raices-que-se-con-514076.webp\",transition: \"fade2\",transitionDuration: 5000},{src: \"https:\/\/nuestrosescritores.com\/sabelagondulfes\/wp-content\/uploads\/sites\/224\/2025\/11\/Firefly_Runway_-Semilla-de-luz-flotando-en-un-vasto-cosmos-oscuro-de-ella-emergen-raices-que-se-con-12035.webp\",transition: \"fade2\",transitionDuration: 5000},{src: \"\",transition: \"fade2\",transitionDuration: 5000},{src: \"https:\/\/nuestrosescritores.com\/sabelagondulfes\/wp-content\/uploads\/sites\/224\/2025\/11\/Firefly_Flux_-Dos-figuras-humanas-estilizadas-danzando-en-el-espacio-sus-cuerpos-formados-por-con-827074.webp\",transition: \"fade2\",transitionDuration: 5000},{src: \"https:\/\/nuestrosescritores.com\/sabelagondulfes\/wp-content\/uploads\/sites\/224\/2025\/11\/Firefly_Flux_-Dos-figuras-humanas-estilizadas-danzando-en-el-espacio-sus-cuerpos-formados-por-con-514076.webp\",transition: \"fade2\",transitionDuration: 5000},]\n    });\t\t\n})(jQuery);\n<\/script><div class=\"rowvcpt-overlay\" style=\"background:rgba(255,255,255,0.69)\"><\/div><\/div><div id=\"uvc-type-wrap-8079\"  data-ultimate-target='#uvc-type-wrap-8079'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  class=\"uvc-type-wrap vc_custom_1764433493658 ult-adjust-bottom-margin ult-responsive  uvc-type-align-center uvc-type-no-prefix uvc-wrap-41280250806a93ab83501da\" style=\"text-align:center;\"><span id=\"typed-41280250806a93ab83501da\" class=\"ultimate-typed-main \" style=\" font-weight:bold; text-transform: unset;\"><\/span><script type=\"text\/javascript\">\n\t\t\t\t\t\tjQuery(function($){ \n\t\t\t\t\t\t\t$(document).ready(function(){\n\t\t\t\t\t\t\t\tif( typeof jQuery(\"#typed-41280250806a93ab83501da\").typed == \"function\"){\n\t\t\t\t\t\t\t\t\t$(\"#typed-41280250806a93ab83501da\").typed({\n\t\t\t\t\t\t\t\t\t\tstrings: [\"Sabela Gondulfes (Gondulfes, Ourense)\",\"Escribo desde que no sab\u00eda escribir, entonces lo hac\u00eda a garabatos. A trav\u00e9s de la narrativa, cr\u00f3nica, oratoria, dramaturgia, poes\u00eda, me voy construyendo y deconstruyendo y construyendo. Siempre digo que, si no escribiera, no, necesariamente, en un papel o en un archivo, morir\u00eda de inanici\u00f3n. Experimento tambi\u00e9n con otras artes, a la fecha, casi s\u00f3lo para que me ayuden a hilvanar palabras en la intimidad.\",\"Libros publicados e in\u00e9ditos para destacar, Deshilachando Banderas, Nadar Ediciones, cr\u00f3nicas de viaje y testimonio, escrito durante un invierno en el Desierto de Atacama. PieLanDo, Ediciones Una Temporada en Isla Negra, presentado en Fundaci\u00f3n Neruda, libro fusi\u00f3n. Con el alma en los pies y el coraz\u00f3n en las manos, Edici\u00f3n Personal, poes\u00eda. Aram\u00ed y Aram\u00ed en los MunD2, ensayo ficci\u00f3n, in\u00e9ditas. Inv\u00e9ntame la Vida, comedia rom\u00e1ntica en colaboraci\u00f3n con C\u00e9sar P\u00f3o, \u00e9l cre\u00f3 al personaje principal femenino y sus secundarios, yo al protagonista masculino y los de reparto. La creamos comunic\u00e1ndonos de forma epistolar. Siempre he cultivado este g\u00e9nero. En la Penumbra, Fundaci\u00f3n Opera Prima, finalista en V certamen internacional de novela Lu\u00eds Berenguer. Estoy incluida en varias antolog\u00edas de poes\u00eda y narrativa iberoamericana, Gira Poema 2009, Santiago de Chile~Nueva York, la m\u00e1s apreciada. M\u00faltiples poemas m\u00edos han sido musicalizados, Jazz fusi\u00f3n, principalmente, y traducidos a otros idiomas, chino, ruso, italiano, georgiano.\",\"He residido en diversos lugares, cortas y largas temporadas, entre ellos, la Patagonia, Argentina, Isla Negra, Valpara\u00edso, Desierto de Atacama, Chile, Nueva York, la Breta\u00f1a, Florencia, Lisboa, Madrid.\",\"Mis intereses son vivir en constante aprendizaje y transformaci\u00f3n. Sentido del humor y del amor a raudales. Las cerezas Napole\u00f3n y las del Valle del Jerte tambi\u00e9n, com\u00e9rmelas, y hasta me atrevo a trepar a por ellas. La familia. La amistad. T\u00fa que me est\u00e1s leyendo. Que la muerte me pille viva. Transcender despu\u00e9s de ella. Caminar lenta, r\u00e1pido. Peregrinar. La pol\u00edtica, las personas de la pol\u00edtica actuales cada vez menos. La antropolog\u00eda, el trabajo de campo. La conciliaci\u00f3n de las diferentes culturas y pueblos. BAILAR. CANTAR. COSER LOS TOMATES DE LOS CALCETINES. TERNURA. COCINAR PARA 2. ORAR. BA\u00d1ARME EN EL MAR AL RITMO DE LAS OLAS. GRITAR CUANDO NADIE ME OYE, \u2014los otros gritos ya los dej\u00e9 atr\u00e1s, a veces vuelven y los callo con los, cuando nadie me oye. VIVIR COMO SI FUERA HOY EL PRIMER D\u00cdA. CREER QUE NO ES EL \u00daLTIMO.\"],\n\t\t\t\t\t\t\t\t\t\ttypeSpeed: 35,\n\t\t\t\t\t\t\t\t\t\tbackSpeed: 0,\n\t\t\t\t\t\t\t\t\t\tstartDelay: \"200\",\n\t\t\t\t\t\t\t\t\t\tbackDelay: \"1500\",\n\t\t\t\t\t\t\t\t\t\tloop: true,\n\t\t\t\t\t\t\t\t\t\tloopCount: false,\n\t\t\t\t\t\t\t\t\t\tshowCursor: true,\n\t\t\t\t\t\t\t\t\t\tcursorChar: \"|\",\n\t\t\t\t\t\t\t\t\t\tattr: null\n\t\t\t\t\t\t\t\t\t});\n\t\t\t\t\t\t\t\t}\n\t\t\t\t\t\t\t});\n\t\t\t\t\t\t});\n\t\t\t\t\t<\/script><\/div>[\/vc_column][\/vc_row][vc_row full_height=&#8221;yes&#8221; equal_height=&#8221;yes&#8221;][vc_column extend=&#8221;false&#8221;]<div id=\"rowvcpt-row-settings\" class=\"rowvcpt-row-set RowVcPt-row-setting6a93ab8350623 \" data-no=\"RowVcPt-row-setting6a93ab8350623\"><div class=\"columns-bg-wrap columns-bg-anim-colors columns-bg-image  columns_simple_image\" id=\"RowVcPt-image-bg-6a93ab8350622\"   data-parallax_sense=\"30\" src=\"https:\/\/nuestrosescritores.com\/sabelagondulfes\/wp-content\/uploads\/sites\/224\/2025\/11\/Firefly_Flux_Silueta-femenina-integrada-con-paisaje-de-montanas-gallegas-al-atardecer-su-cabello-492468_1.webp\" style=\"background-image: url(https:\/\/nuestrosescritores.com\/sabelagondulfes\/wp-content\/uploads\/sites\/224\/2025\/11\/Firefly_Flux_Silueta-femenina-integrada-con-paisaje-de-montanas-gallegas-al-atardecer-su-cabello-492468_1.webp);background-position: left center;background-size: cover;background-attachment: fixed;\"><\/div><\/div>[vc_column_text css=&#8221;&#8221;]\n<p style=\"text-align: center;\"><a class=\"fasc-button fasc-size-xlarge fasc-type-glossy fasc-rounded-medium\" style=\"background-color: #2f9e38; color: #ffffff;\" href=\"https:\/\/gepa.es\/producto\/afouteza-certeca-sabela-gondulfes\/\">COMPRA SUS LIBROS<\/a><\/p>\n[\/vc_column_text][\/vc_column][\/vc_row]\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row full_width=&#8221;stretch_row_content_no_spaces&#8221; full_height=&#8221;yes&#8221; equal_height=&#8221;yes&#8221;][vc_column extend=&#8221;false&#8221;][layerslider_vc id=&#8221;2&#8243;][layerslider_vc id=&#8221;1&#8243;][\/vc_column][\/vc_row][vc_row extend=&#8221;false&#8221; design__empty_1=&#8221;&#8221; background=&#8221;&#8221; background_image_type=&#8221;static&#8221; background_image__effect=&#8221;&#8221; bg_size=&#8221;initial&#8221; bg_position=&#8221;center-center&#8221; row_bg_image=&#8221;&#8221; bg_repeat=&#8221;no-repeat&#8221; background_image_type__bg_color=&#8221;rgba(255, 255, 255, 1)&#8221; row_bg_parallax_images=&#8221;&#8221; row_bg_slideshow_images=&#8221;&#8221; background_video_type=&#8221;youtube&#8221; background_video__youtube__url=&#8221;&#8221; background_video__youtube__parallax=&#8221;&#8221; background_video__youtube__options=&#8221;&#8221; background_video__youtube__fallback_image=&#8221;&#8221; background_video__hosted__mp4=&#8221;&#8221; background_video__hosted__webm=&#8221;&#8221; background_video__hosted__ogv=&#8221;&#8221; background_video__hosted__parallax=&#8221;&#8221; background_video__hosted__options=&#8221;&#8221; background_video__hosted__fallback_image=&#8221;&#8221; background_color_type=&#8221;color&#8221; bg__empty_1=&#8221;&#8221; background_color_type__gradient_color1=&#8221;rgba(44, 74, 228, 1)&#8221; background_color_type__gradient_color2=&#8221;rgba(44, 74, 228, 1)&#8221; background_color_type__color_color1=&#8221;rgba(44, 74, 228, 1)&#8221; bg__empty_2=&#8221;&#8221; background_color__effect=&#8221;&#8221; background_color__direction=&#8221;left-to-right&#8221; settings__tag_1=&#8221;&#8221; viewport_lg=&#8221;&#8221; viewport_md=&#8221;&#8221; viewport_sm=&#8221;&#8221; viewport_xs=&#8221;&#8221; [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":27,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-11","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.5 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>SABELA GONDULFES - Sabela Gondulfes<\/title>\n<meta name=\"description\" content=\"SABELA GONDULFES es la escritora del libro AFOUTEZA &amp; CERTE\u00c7A . La escritora acaba de publicar un libro con la Editorial Poes\u00eda eres t\u00fa.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nuestrosescritores.com\/sabelagondulfes\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SABELA GONDULFES\" \/>\n<meta property=\"og:description\" content=\"SABELA GONDULFES es la escritora del libro AFOUTEZA &amp; CERTE\u00c7A . La escritora acaba de publicar un libro con la Editorial Poes\u00eda eres t\u00fa.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nuestrosescritores.com\/sabelagondulfes\/\" \/>\n<meta property=\"og:site_name\" content=\"Sabela Gondulfes\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-29T22:29:34+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/nuestrosescritores.com\/sabelagondulfes\/wp-content\/uploads\/sites\/224\/2025\/11\/SABELA-scaled.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1282\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nuestrosescritores.com\\\/sabelagondulfes\\\/\",\"url\":\"https:\\\/\\\/nuestrosescritores.com\\\/sabelagondulfes\\\/\",\"name\":\"SABELA GONDULFES - Sabela Gondulfes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nuestrosescritores.com\\\/sabelagondulfes\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/nuestrosescritores.com\\\/sabelagondulfes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/nuestrosescritores.com\\\/sabelagondulfes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nuestrosescritores.com\\\/sabelagondulfes\\\/wp-content\\\/uploads\\\/sites\\\/224\\\/2025\\\/11\\\/SABELA-scaled.webp\",\"datePublished\":\"2025-11-29T16:26:08+00:00\",\"dateModified\":\"2025-11-29T22:29:34+00:00\",\"description\":\"SABELA GONDULFES es la escritora del libro AFOUTEZA & CERTE\u00c7A . La escritora acaba de publicar un libro con la Editorial Poes\u00eda eres t\u00fa.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nuestrosescritores.com\\\/sabelagondulfes\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nuestrosescritores.com\\\/sabelagondulfes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/nuestrosescritores.com\\\/sabelagondulfes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/nuestrosescritores.com\\\/sabelagondulfes\\\/wp-content\\\/uploads\\\/sites\\\/224\\\/2025\\\/11\\\/SABELA-scaled.webp\",\"contentUrl\":\"https:\\\/\\\/nuestrosescritores.com\\\/sabelagondulfes\\\/wp-content\\\/uploads\\\/sites\\\/224\\\/2025\\\/11\\\/SABELA-scaled.webp\",\"width\":2560,\"height\":1282},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nuestrosescritores.com\\\/sabelagondulfes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/nuestrosescritores.com\\\/sabelagondulfes\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SABELA GONDULFES\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nuestrosescritores.com\\\/sabelagondulfes\\\/#website\",\"url\":\"https:\\\/\\\/nuestrosescritores.com\\\/sabelagondulfes\\\/\",\"name\":\"Nuestros escritores\",\"description\":\"Escritora\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nuestrosescritores.com\\\/sabelagondulfes\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"SABELA GONDULFES - Sabela Gondulfes","description":"SABELA GONDULFES es la escritora del libro AFOUTEZA & CERTE\u00c7A . La escritora acaba de publicar un libro con la Editorial Poes\u00eda eres t\u00fa.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nuestrosescritores.com\/sabelagondulfes\/","og_locale":"es_ES","og_type":"article","og_title":"SABELA GONDULFES","og_description":"SABELA GONDULFES es la escritora del libro AFOUTEZA & CERTE\u00c7A . La escritora acaba de publicar un libro con la Editorial Poes\u00eda eres t\u00fa.","og_url":"https:\/\/nuestrosescritores.com\/sabelagondulfes\/","og_site_name":"Sabela Gondulfes","article_modified_time":"2025-11-29T22:29:34+00:00","og_image":[{"width":2560,"height":1282,"url":"http:\/\/nuestrosescritores.com\/sabelagondulfes\/wp-content\/uploads\/sites\/224\/2025\/11\/SABELA-scaled.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nuestrosescritores.com\/sabelagondulfes\/","url":"https:\/\/nuestrosescritores.com\/sabelagondulfes\/","name":"SABELA GONDULFES - Sabela Gondulfes","isPartOf":{"@id":"https:\/\/nuestrosescritores.com\/sabelagondulfes\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nuestrosescritores.com\/sabelagondulfes\/#primaryimage"},"image":{"@id":"https:\/\/nuestrosescritores.com\/sabelagondulfes\/#primaryimage"},"thumbnailUrl":"https:\/\/nuestrosescritores.com\/sabelagondulfes\/wp-content\/uploads\/sites\/224\/2025\/11\/SABELA-scaled.webp","datePublished":"2025-11-29T16:26:08+00:00","dateModified":"2025-11-29T22:29:34+00:00","description":"SABELA GONDULFES es la escritora del libro AFOUTEZA & CERTE\u00c7A . La escritora acaba de publicar un libro con la Editorial Poes\u00eda eres t\u00fa.","breadcrumb":{"@id":"https:\/\/nuestrosescritores.com\/sabelagondulfes\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nuestrosescritores.com\/sabelagondulfes\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/nuestrosescritores.com\/sabelagondulfes\/#primaryimage","url":"https:\/\/nuestrosescritores.com\/sabelagondulfes\/wp-content\/uploads\/sites\/224\/2025\/11\/SABELA-scaled.webp","contentUrl":"https:\/\/nuestrosescritores.com\/sabelagondulfes\/wp-content\/uploads\/sites\/224\/2025\/11\/SABELA-scaled.webp","width":2560,"height":1282},{"@type":"BreadcrumbList","@id":"https:\/\/nuestrosescritores.com\/sabelagondulfes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/nuestrosescritores.com\/sabelagondulfes\/"},{"@type":"ListItem","position":2,"name":"SABELA GONDULFES"}]},{"@type":"WebSite","@id":"https:\/\/nuestrosescritores.com\/sabelagondulfes\/#website","url":"https:\/\/nuestrosescritores.com\/sabelagondulfes\/","name":"Nuestros escritores","description":"Escritora","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nuestrosescritores.com\/sabelagondulfes\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/nuestrosescritores.com\/sabelagondulfes\/wp-json\/wp\/v2\/pages\/11","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nuestrosescritores.com\/sabelagondulfes\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/nuestrosescritores.com\/sabelagondulfes\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/nuestrosescritores.com\/sabelagondulfes\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nuestrosescritores.com\/sabelagondulfes\/wp-json\/wp\/v2\/comments?post=11"}],"version-history":[{"count":0,"href":"https:\/\/nuestrosescritores.com\/sabelagondulfes\/wp-json\/wp\/v2\/pages\/11\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nuestrosescritores.com\/sabelagondulfes\/wp-json\/wp\/v2\/media\/27"}],"wp:attachment":[{"href":"https:\/\/nuestrosescritores.com\/sabelagondulfes\/wp-json\/wp\/v2\/media?parent=11"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}